{"id":7111,"date":"2012-11-26T10:29:53","date_gmt":"2012-11-26T15:29:53","guid":{"rendered":"http:\/\/www.jemeprendsenmain.ca\/?p=3138"},"modified":"2021-09-17T11:13:06","modified_gmt":"2021-09-17T15:13:06","slug":"devrait-on-compter-les-calories","status":"publish","type":"post","link":"https:\/\/www.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/","title":{"rendered":"Devrait-on compter les calories?"},"content":{"rendered":"\n<p>Avez-vous d\u00e9j\u00e0 entendu parler de la balance \u00e9nerg\u00e9tique? Il s\u2019agit du principe r\u00e9gissant le gain, la perte ou le maintien du poids. En effet, c\u2019est l\u2019\u00e9quilibre entre votre apport \u00e9nerg\u00e9tique, soit la quantit\u00e9 de calories que vous ing\u00e9rez quotidiennement sous forme d\u2019aliments et de breuvages, et votre d\u00e9pense \u00e9nerg\u00e9tique quotidienne, soit les calories d\u00e9pens\u00e9es par le m\u00e9tabolisme de base de votre corps, vos activit\u00e9s quotidiennes (travailler assis ou sur la construction, par exemple), et vos activit\u00e9s physiques.<\/p>\n\n\n\n<p><strong>Prendre conscience du nombre de calories que l\u2019on ing\u00e8re quotidiennement est un \u00e9l\u00e9ment essentiel lors d\u2019un processus de perte de poids<\/strong>. Par contre, il ne faut pas que ce soit notre seule strat\u00e9gie. En plus d\u2019int\u00e9grer l\u2019activit\u00e9 physique \u00e0 notre d\u00e9marche, il faut \u00e9galement faire de bons choix alimentaires.<\/p>\n\n\n\n<p>En effet, les aliments poss\u00e8dent des macronutriments, soit les lipides, les glucides et les prot\u00e9ines, ainsi que des micronutriments, comme le calcium et le fer, pour ne nommer que ceux-ci. Les gens qui cherchent \u00e0 consommer le moins de calories possible, et qui garnissent leur panier d\u2019\u00e9picerie en ce sens, se retrouvent souvent avec un panier \u00ab vide \u00bb : vide de nutriments! <strong>Sachez que m\u00eame si vous fournissez \u00e0 votre corps le nombre de calories dont il a besoin, s\u2019il ne re\u00e7oit pas les nutriments dont il a besoin, il vous enverra des signaux de faim.<\/strong> C\u2019est pourquoi, si vous avez besoin de 1 800 calories quotidiennement, et que vous mangez 1 800 calories sous forme de croustilles, th\u00e9oriquement, vous n\u2019engraisserez pas\u2026 Mais votre corps vous enverra des signaux de faim \u00e0 nouveau pour combler ses besoins en nutriments, et vous vous retrouverez en surplus \u00e9nerg\u00e9tique.<\/p>\n\n\n\n<p>Que devriez-vous faire?<\/p>\n\n\n\n<ol><li><strong>Choisir des aliments \u00e0 plus faible densit\u00e9 \u00e9nerg\u00e9tique<br><\/strong>C&rsquo;est-\u00e0-dire choisir des aliments qui contiennent moins de calories pour un plus grand volume, comme les fruits et les l\u00e9gumes, ce qui favorise la sensation de sati\u00e9t\u00e9<a href=\"#_ftn1_4037\" name=\"_ftnref1_4037\"><\/a>[1].<\/li><li><strong>Bien lire les \u00e9tiquettes nutritionnelles<br><\/strong>Choisissez des aliments sains et nutritifs. Comparez des produits similaires et choisissez celui qui contient le plus de nutriments possibles pour un nombre de calories comparable. Pour \u00eatre bien outill\u00e9s \u00e0 cet effet, je vous sugg\u00e8re de lire l\u2019article <em><a href=\"https:\/\/www.nautilusplus.com\/fr\/blogue\/lire-les-tiquettes-nutritionnelles-simple-comme-bonjour\/\">Lire les \u00e9tiquettes nutritionnelles : simple comme bonjour<\/a><\/em>.<\/li><li><strong>\u00c9coutez vos signaux de faim et de sati\u00e9t\u00e9<br><\/strong>Votre corps vous indique s\u2019il a besoin d\u2019\u00e9nergie ou s\u2019il en a re\u00e7u suffisamment. Il serait tellement plus simple de l\u2019\u00e9couter, plut\u00f4t que de calculer! Bien qu\u2019il faille tout de m\u00eame prendre conscience de la quantit\u00e9 de calories que l\u2019on mange, il faut aussi savoir \u00e9couter notre corps. Je vous sugg\u00e8re de lire \u00e0 ce sujet l\u2019article <em><a href=\"https:\/\/www.nautilusplus.com\/fr\/blogue\/votre-apptit-vous-joue-des-tours\/\">Votre app\u00e9tit vous joue des tours<\/a>?<\/em><\/li><\/ol>\n\n\n\n<p>Qu\u2019en pensez-vous?<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-small-font-size\"><a href=\"#_ftnref1_4037\" name=\"_ftn1_4037\"><\/a>[1] Baribeau, H\u00e9l\u00e8ne. Passeport sant\u00e9 http:\/\/www.passeportsante.net\/fr\/Nutrition\/Regimes\/Fiche.aspx?doc=densite_energetique_regime<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avez-vous d\u00e9j\u00e0 entendu parler de la balance \u00e9nerg\u00e9tique? Il s\u2019agit du principe r\u00e9gissant le gain, la perte ou le maintien du poids. En effet, c\u2019est l\u2019\u00e9quilibre entre votre apport \u00e9nerg\u00e9tique, soit la quantit\u00e9 de calories que vous ing\u00e9rez quotidiennement sous forme d\u2019aliments et de breuvages, et votre d\u00e9pense \u00e9nerg\u00e9tique quotidienne, soit les calories d\u00e9pens\u00e9es par [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":5893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5681,5193],"tags":[2234,2235,1732,1321],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Devrait-on compter les calories? - Nautilus Plus\" \/>\r\n<meta property=\"og:description\" content=\"Avez-vous d\u00e9j\u00e0 entendu parler de la balance \u00e9nerg\u00e9tique? Il s\u2019agit du principe r\u00e9gissant le gain, la perte ou le maintien du poids. En effet, c\u2019est l\u2019\u00e9quilibre entre votre apport \u00e9nerg\u00e9tique, soit la quantit\u00e9 de calories que vous ing\u00e9rez quotidiennement sous forme d\u2019aliments et de breuvages, et votre d\u00e9pense \u00e9nerg\u00e9tique quotidienne, soit les calories d\u00e9pens\u00e9es par [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Nautilus Plus\" \/>\r\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nautilusplus\" \/>\r\n<meta property=\"article:published_time\" content=\"2012-11-26T15:29:53+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-09-17T15:13:06+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.nautilusplus.com\/content\/uploads\/2012\/11\/Counting-calories1.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"849\" \/>\r\n\t<meta property=\"og:image:height\" content=\"565\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#website\",\"url\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"name\":\"Nautilus Plus\",\"description\":\"Plus qu&#039;un gym\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.nautilusplus.com\/fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2012\/11\/Counting-calories1.jpg\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2012\/11\/Counting-calories1.jpg\",\"width\":849,\"height\":565},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/#webpage\",\"url\":\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/\",\"name\":\"Devrait-on compter les calories? - Nautilus Plus\",\"isPartOf\":{\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/#primaryimage\"},\"datePublished\":\"2012-11-26T15:29:53+00:00\",\"dateModified\":\"2021-09-17T15:13:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#\/schema\/person\/d1896eeaebe531fd4af7f22e29ceb51a\"},\"breadcrumb\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"url\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/devrait-on-compter-les-calories\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#\/schema\/person\/d1896eeaebe531fd4af7f22e29ceb51a\",\"name\":\"Nautilus Plus\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/03\/NautilusPlus_fond-bleu-96x96.jpg\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/03\/NautilusPlus_fond-bleu-96x96.jpg\",\"caption\":\"Nautilus Plus\"},\"sameAs\":[\"http:\/\/www.NautilusPlus.com\",\"https:\/\/www.facebook.com\/nautilusplus\",\"https:\/\/twitter.com\/Nautilus_Plus\"],\"url\":\"https:\/\/www.nautilusplus.com\/fr\/author\/nautilusplus\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/7111"}],"collection":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/comments?post=7111"}],"version-history":[{"count":0,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/7111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media\/5893"}],"wp:attachment":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media?parent=7111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/categories?post=7111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/tags?post=7111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}