{"id":20839,"date":"2015-06-30T11:53:04","date_gmt":"2015-06-30T15:53:04","guid":{"rendered":"http:\/\/www.nautilusplus.com\/?p=20839"},"modified":"2024-11-14T11:09:07","modified_gmt":"2024-11-14T16:09:07","slug":"gruau-onctueux-lananas-et-la-cannelle","status":"publish","type":"post","link":"https:\/\/www.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/","title":{"rendered":"Gruau onctueux \u00e0 l\u2019ananas et \u00e0 la cannelle"},"content":{"rendered":"\n<p>J\u2019adore le gruau sous toutes ses formes. Les combinaisons sont illimit\u00e9es et toujours savoureuses. Je vous donne ici l\u2019une de mes combinaisons favorites, qui go\u00fbte comme un renvers\u00e9 \u00e0 l\u2019ananas. Je pr\u00e9f\u00e8re faire cette recette au micro-ondes gr\u00e2ce \u00e0 sa texture qui est beaucoup plus onctueuse et moins liquide qu\u2019avec la cuisini\u00e8re. C\u2019est surtout moins long et il n\u2019y a pas de vaisselle \u00e0 faire!<\/p>\n\n\n\n<p><strong>1 portion<\/strong><\/p>\n\n\n\n<h3><strong>Ingr\u00e9dients<\/strong><\/h3>\n\n\n\n<p>250&nbsp;ml (1 tasse) d\u2019ananas, tranch\u00e9 en d\u00e9s<br>250&nbsp;ml (1 tasse) de lait d\u2019amande enrichi non sucr\u00e9<br>80&nbsp;ml (1\/3 tasse) flocons d\u2019avoine<br>5&nbsp;ml (1 c. \u00e0 th\u00e9) d\u2019extrait de vanille<br>10&nbsp;ml (2 c. \u00e0 th\u00e9) de cannelle<br>5&nbsp;ml (1 c. \u00e0 th\u00e9) de sirop d\u2019\u00e9rable<br>125&nbsp;ml (1\/2 tasse) de yogourt grec nature 0&nbsp;% M.G.<br>8 pacanes, hach\u00e9es<\/p>\n\n\n\n<h3><strong>Pr\u00e9paration<\/strong><\/h3>\n\n\n\n<ol>\n<li>Dans un bol, ajouter les ananas, les flocons d\u2019avoine, le lait d\u2019amande, la vanille, la cannelle et 5&nbsp;ml (1 c. \u00e0 th\u00e9) de sirop d\u2019\u00e9rable, puis m\u00e9langer.<\/li>\n\n\n\n<li>Cuire au micro-ondes \u00e0 haute intensit\u00e9 jusqu\u2019\u00e0 ce que l\u2019avoine absorbe le liquide et qu\u2019il obtienne une texture tr\u00e8s onctueuse. Je vous sugg\u00e8re de le cuire durant 5 \u00e0 8 minutes, d\u00e9pendamment du micro-ondes.<\/li>\n\n\n\n<li>Dans un bol, m\u00e9langer le yogourt grec avec le sirop d\u2019\u00e9rable restant (5&nbsp;ml ou 1 c. \u00e0 th\u00e9). R\u00e9server.<\/li>\n\n\n\n<li>Lorsque le gruau est pr\u00eat, garnir de yogourt et de pacanes.<\/li>\n<\/ol>\n\n\n\n<p><strong>Cette recette contient par portion :<\/strong><\/p>\n\n\n\n<p>428 calories \/ 60&nbsp;g glucides \/ 14&nbsp;g gras \/ 20&nbsp;g prot\u00e9ines \/ 10&nbsp;g fibres<\/p>\n\n\n\n<p>1 fruit, 1 f\u00e9culent, 1 viande et substituts, 1 sucre, 1 gras.<\/p>\n\n\n\n<p>Bon app\u00e9tit!<\/p>\n\n\n\n<p>Par Sophie Blais<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Pour d&rsquo;autres id\u00e9es recettes : <\/p>\n\n\n\n<ul>\n<li><a href=\"\/gruau-overnight-cremeux-choco-arachide-et-banane\/\">Gruau overnight cr\u00e9meux choco, arachide et banane\u00a0<\/a><\/li>\n\n\n\n<li><a href=\"\/bol-de-smoothie-proteine-au-granola\/\">Bol de smoothie prot\u00e9in\u00e9 au granola<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019adore le gruau sous toutes ses formes. Les combinaisons sont illimit\u00e9es et toujours savoureuses. Je vous donne ici l\u2019une de mes combinaisons favorites, qui go\u00fbte comme un renvers\u00e9 \u00e0 l\u2019ananas. Je pr\u00e9f\u00e8re faire cette recette au micro-ondes gr\u00e2ce \u00e0 sa texture qui est beaucoup plus onctueuse et moins liquide qu\u2019avec la cuisini\u00e8re. C\u2019est surtout moins [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":20837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5190,1267],"tags":[2702,227,3935,110,144],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<meta name=\"description\" content=\"J\u2019adore le gruau sous toutes ses formes. Les combinaisons sont illimit\u00e9es et toujours savoureuses. C&#039;est comme un renvers\u00e9 \u00e0 l\u2019ananas.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Gruau onctueux \u00e0 l\u2019ananas et \u00e0 la cannelle\" \/>\r\n<meta property=\"og:description\" content=\"J\u2019adore le gruau sous toutes ses formes. Les combinaisons sont illimit\u00e9es et toujours savoureuses. C&#039;est comme un renvers\u00e9 \u00e0 l\u2019ananas.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Nautilus Plus\" \/>\r\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nautilusplus\" \/>\r\n<meta property=\"article:published_time\" content=\"2015-06-30T15:53:04+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-11-14T16:09:07+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.nautilusplus.com\/content\/uploads\/2015\/06\/Gruau-ananas.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"800\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#website\",\"url\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"name\":\"Nautilus Plus\",\"description\":\"Plus qu&#039;un gym\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.nautilusplus.com\/fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2015\/06\/Gruau-ananas.jpg\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2015\/06\/Gruau-ananas.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/#webpage\",\"url\":\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/\",\"name\":\"Gruau onctueux \\u00e0 l\\u2019ananas et \\u00e0 la cannelle - Nautilus Plus\",\"isPartOf\":{\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/#primaryimage\"},\"datePublished\":\"2015-06-30T15:53:04+00:00\",\"dateModified\":\"2024-11-14T16:09:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#\/schema\/person\/d1896eeaebe531fd4af7f22e29ceb51a\"},\"description\":\"J\\u2019adore le gruau sous toutes ses formes. Les combinaisons sont illimit\\u00e9es et toujours savoureuses. C'est comme un renvers\\u00e9 \\u00e0 l\\u2019ananas.\",\"breadcrumb\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"url\":\"https:\/\/www.nautilusplus.com\/fr\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/cms.nautilusplus.com\/fr\/gruau-onctueux-lananas-et-la-cannelle\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#\/schema\/person\/d1896eeaebe531fd4af7f22e29ceb51a\",\"name\":\"Nautilus Plus\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.nautilusplus.com\/fr\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/03\/NautilusPlus_fond-bleu-96x96.jpg\",\"contentUrl\":\"https:\/\/www.nautilusplus.com\/content\/uploads\/2020\/03\/NautilusPlus_fond-bleu-96x96.jpg\",\"caption\":\"Nautilus Plus\"},\"sameAs\":[\"http:\/\/www.NautilusPlus.com\",\"https:\/\/www.facebook.com\/nautilusplus\",\"https:\/\/twitter.com\/Nautilus_Plus\"],\"url\":\"https:\/\/www.nautilusplus.com\/fr\/author\/nautilusplus\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/20839"}],"collection":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/comments?post=20839"}],"version-history":[{"count":0,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/posts\/20839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media\/20837"}],"wp:attachment":[{"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/media?parent=20839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/categories?post=20839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nautilusplus.com\/fr\/wp-json\/wp\/v2\/tags?post=20839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}